{"id":12377,"date":"2025-04-25T12:03:09","date_gmt":"2025-04-25T10:03:09","guid":{"rendered":"https:\/\/mo2drive.com\/?page_id=12377"},"modified":"2025-05-06T11:03:07","modified_gmt":"2025-05-06T09:03:07","slug":"rent-a-vespa","status":"publish","type":"page","link":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/","title":{"rendered":"Rent a Vespa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-home-alt.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-12377","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rent a Vespa - mo2drive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mo2drive.com\/en\/rent-a-vespa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rent a Vespa - mo2drive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mo2drive.com\/en\/rent-a-vespa\/\" \/>\n<meta property=\"og:site_name\" content=\"mo2drive\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T09:03:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/rent-a-vespa\\\/\",\"url\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/rent-a-vespa\\\/\",\"name\":\"Rent a Vespa - mo2drive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/#website\"},\"datePublished\":\"2025-04-25T10:03:09+00:00\",\"dateModified\":\"2025-05-06T09:03:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/rent-a-vespa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mo2drive.com\\\/en\\\/rent-a-vespa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/rent-a-vespa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rent a Vespa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/\",\"name\":\"mo2drive\",\"description\":\"Deine Vespa Vermietung\",\"publisher\":{\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/#organization\",\"name\":\"mo2drive\",\"url\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mo2drive.com\\\/wp-content\\\/uploads\\\/mo2drive-logo.png\",\"contentUrl\":\"https:\\\/\\\/mo2drive.com\\\/wp-content\\\/uploads\\\/mo2drive-logo.png\",\"width\":412,\"height\":276,\"caption\":\"mo2drive\"},\"image\":{\"@id\":\"https:\\\/\\\/mo2drive.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rent a Vespa - mo2drive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/","og_locale":"en_US","og_type":"article","og_title":"Rent a Vespa - mo2drive","og_url":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/","og_site_name":"mo2drive","article_modified_time":"2025-05-06T09:03:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/","url":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/","name":"Rent a Vespa - mo2drive","isPartOf":{"@id":"https:\/\/mo2drive.com\/en\/#website"},"datePublished":"2025-04-25T10:03:09+00:00","dateModified":"2025-05-06T09:03:07+00:00","breadcrumb":{"@id":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mo2drive.com\/en\/rent-a-vespa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mo2drive.com\/en\/rent-a-vespa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mo2drive.com\/en\/"},{"@type":"ListItem","position":2,"name":"Rent a Vespa"}]},{"@type":"WebSite","@id":"https:\/\/mo2drive.com\/en\/#website","url":"https:\/\/mo2drive.com\/en\/","name":"mo2drive","description":"Deine Vespa Vermietung","publisher":{"@id":"https:\/\/mo2drive.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mo2drive.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mo2drive.com\/en\/#organization","name":"mo2drive","url":"https:\/\/mo2drive.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mo2drive.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mo2drive.com\/wp-content\/uploads\/mo2drive-logo.png","contentUrl":"https:\/\/mo2drive.com\/wp-content\/uploads\/mo2drive-logo.png","width":412,"height":276,"caption":"mo2drive"},"image":{"@id":"https:\/\/mo2drive.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/pages\/12377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/comments?post=12377"}],"version-history":[{"count":5,"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/pages\/12377\/revisions"}],"predecessor-version":[{"id":12386,"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/pages\/12377\/revisions\/12386"}],"wp:attachment":[{"href":"https:\/\/mo2drive.com\/en\/wp-json\/wp\/v2\/media?parent=12377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}